{"id":5286,"date":"2024-08-30T09:40:45","date_gmt":"2024-08-30T12:40:45","guid":{"rendered":"https:\/\/sedesur.unsa.edu.ar\/?p=5286"},"modified":"2024-08-30T09:40:54","modified_gmt":"2024-08-30T12:40:54","slug":"llamado-a-inscripcion-teu-metan","status":"publish","type":"post","link":"https:\/\/sedesur.unsa.edu.ar\/index.php\/2024\/08\/30\/llamado-a-inscripcion-teu-metan\/","title":{"rendered":"LLAMADO A INSCRIPCI\u00d3N &#8211; TEU &#8211; MET\u00c1N"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5286\" class=\"elementor elementor-5286\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b53d90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b53d90\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d2b575\" data-id=\"2d2b575\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d0090d elementor-widget elementor-widget-text-editor\" data-id=\"7d0090d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Facultad de Ciencias Exactas de la Universidad Nacional de Salta,\u00a0<span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">mediante RD: 706\/2024-EXA-UNSa, Llamado a Inscripci\u00f3n de interesados para\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">cubrir un (1) cargo de Graduado Adscripto para la asignatura Introducci\u00f3n a\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">los Circuitos El\u00e9ctricos de la carrera de Tecnicatura Electr\u00f3nica <\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">Universitaria (plan 2006), que se dicta en la Sede Regional Met\u00e1n- Rosario\u00a0<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">de la Frontera, con asiento en Met\u00e1n y por el t\u00e9rmino de un (1) a\u00f1o.<\/span><\/p><p>Plan de Trabajo Propuesto consta de las siguientes tareas:\u00a0<br \/>&#8211; Preparaci\u00f3n de trabajos pr\u00e1cticos.<br \/>&#8211; Preparaci\u00f3n de material para la c\u00e1tedra.<br \/>&#8211; B\u00fasqueda y actualizaci\u00f3n de Bibliograf\u00eda.<\/p><p>CRONOGRAMA<\/p><p><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">PUBLICACION: 29 de agosto de 2024<\/span><\/p><p><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">INSCRIPCIONES:\u00a0 03 de septiembre de 2024,<\/span><\/p><p>CIERRE DE INSCRIPCIONES:\u00a0 05 de septiembre de 2024.<\/p><p>EXHIBICI\u00d3N DE N\u00d3MINA DE INSCRIPTOS: 05 de septiembre de 2024<\/p><p>IMPUGNACIONES Y\/O RECUSACIONES: 06 de septiembre de 2024<\/p><p>ENTREVISTA:\u00a0 09 de septiembre de 2024, a las 15:00 horas &#8211; Sede Regional<br \/>Met\u00e1n-Rosario de la Frontera, asiento Met\u00e1n.<\/p><p>INFORMES E INSCRIPCIONES:<\/p><p>SEDE REGIONAL METAN &#8211; ROSARIO DE LA FRONTERA<\/p><p>METAN: de 09:00 a 12:00 horas y de 15:00 a 18:00 horas.<\/p><p>ROSARIO DE LA FRONTERA: de 09:00 a 12:00 horas y de 15:00 a 18:00 horas.<\/p><p>SEDE CENTRAL: Direcci\u00f3n Administrativa de Docencia de la Facultad de<br \/>Ciencias Exactas de 10:00 hs. a 12:00 hs. y de 14:00 hs. a 16:00 hs.<\/p><p>Las inscripciones se realizan mediante nota dirigida al Se. Decano de la<br \/>Facultad de Ciencias Exactas, Mag. Gustavo Daniel GIL, adjuntando un<br \/>Curr\u00edculum Vitae (con todas sus hojas debidamente firmadas) y la respectiva<br \/>documentaci\u00f3n probatoria, en original o copia certificada.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Facultad de Ciencias Exactas de la Universidad Nacional de Salta,\u00a0mediante RD: 706\/2024-EXA-UNSa, Llamado a Inscripci\u00f3n de interesados para\u00a0cubrir un (1) cargo de Graduado Adscripto para la asignatura Introducci\u00f3n a\u00a0los Circuitos El\u00e9ctricos de la carrera de Tecnicatura Electr\u00f3nica Universitaria (plan <a href=\"https:\/\/sedesur.unsa.edu.ar\/index.php\/2024\/08\/30\/llamado-a-inscripcion-teu-metan\/\" class=\"read-more\">Leer mas &#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,25,23],"tags":[],"class_list":["post-5286","post","type-post","status-publish","format-standard","hentry","category-docentes","category-estudiantes","category-novedades"],"_links":{"self":[{"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/5286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5286"}],"version-history":[{"count":4,"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/5286\/revisions"}],"predecessor-version":[{"id":5290,"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/5286\/revisions\/5290"}],"wp:attachment":[{"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sedesur.unsa.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}